{"id":147950,"date":"2026-05-05T10:18:52","date_gmt":"2026-05-05T07:18:52","guid":{"rendered":"https:\/\/e-imdadat.net\/product\/%d8%ba%d8%b7%d8%a7%d8%a1-%d8%a7%d9%83%d9%88%d8%a7%d8%a8-%d9%81%d9%84%d9%8a%d9%86-6-%d8%a7%d9%88%d9%86%d8%b5-%d8%a7%d8%b3-%d8%a8%d8%a7%d9%83\/"},"modified":"2026-05-05T12:19:12","modified_gmt":"2026-05-05T09:19:12","slug":"%d8%ba%d8%b7%d8%a7%d8%a1-%d8%a7%d9%83%d9%88%d8%a7%d8%a8-%d9%81%d9%84%d9%8a%d9%86-6-%d8%a7%d9%88%d9%86%d8%b5-%d8%a7%d8%b3-%d8%a8%d8%a7%d9%83","status":"publish","type":"product","link":"https:\/\/e-imdadat.net\/ar\/product\/%d8%ba%d8%b7%d8%a7%d8%a1-%d8%a7%d9%83%d9%88%d8%a7%d8%a8-%d9%81%d9%84%d9%8a%d9%86-6-%d8%a7%d9%88%d9%86%d8%b5-%d8%a7%d8%b3-%d8%a8%d8%a7%d9%83\/","title":{"rendered":"\u063a\u0637\u0627\u0621 \u0627\u0643\u0648\u0627\u0628 \u0641\u0644\u064a\u0646 6 \u0627\u0648\u0646\u0635 \u0627\u0633 \u0628\u0627\u0643"},"content":{"rendered":"<p>S-Back Cork Cup Cover 6 oz &#8211;&nbsp;&#8211; \u0643&times;10\u0631\u0628\u0637\u0629&times;100\u062d\u0628\u0629 ,&nbsp;\u063a\u0637\u0627\u0621 \u0623\u0643\u0648\u0627\u0628 \u0641\u0644\u064a\u0646 &nbsp;\u0633\u0647\u0644\u0629 \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0644\u062a\u0633\u0647\u064a\u0644 \u0627\u0644\u0634\u0631\u0628 \u0648\u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S-Back Cork Cup Cover 6 oz &#8211;&nbsp;&#8211; \u0643&times;10\u0631\u0628\u0637\u0629&times;100\u062d\u0628\u0629 ,&nbsp;\u063a\u0637\u0627\u0621 \u0623\u0643\u0648\u0627\u0628 \u0641\u0644\u064a\u0646 &nbsp;\u0633\u0647\u0644\u0629 \u0627\u0644\u0627\u0633\u062a\u062e\u062f\u0627\u0645 \u0644\u062a\u0633\u0647\u064a\u0644 \u0627\u0644\u0634\u0631\u0628 \u0648\u0627\u0644\u062d\u0641\u0627\u0638 \u0639\u0644\u0649 \u0627\u0644\u062d\u0631\u0627\u0631\u0629 .<\/p>\n","protected":false},"featured_media":147949,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1959],"product_tag":[],"class_list":["post-147950","product","type-product","status-publish","has-post-thumbnail","product_cat-1959","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/product\/147950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/comments?post=147950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/media\/147949"}],"wp:attachment":[{"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/media?parent=147950"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/product_brand?post=147950"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/product_cat?post=147950"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/e-imdadat.net\/ar\/wp-json\/wp\/v2\/product_tag?post=147950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}